{"id":89293,"date":"2026-09-02T16:39:55","date_gmt":"2026-09-02T14:39:55","guid":{"rendered":"https:\/\/www.liberopensare.com\/?p=89293"},"modified":"2026-09-02T16:45:56","modified_gmt":"2026-09-02T14:45:56","slug":"caldo-artificiale-e-nebbia-chimica-la-geoingegneria-al-suo-apice","status":"publish","type":"post","link":"https:\/\/www.liberopensare.com\/en\/caldo-artificiale-e-nebbia-chimica-la-geoingegneria-al-suo-apice\/","title":{"rendered":"Caldo artificiale e Nebbia chimica: la Geoingegneria al suo Apice"},"content":{"rendered":"<div class=\"xdj266r x14z9mp xat24cr x1lziwak x1vvkbs x126k92a\">\n<pre dir=\"auto\">di<em><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\"> Rosario Marcian\u00f2<\/span><\/em><\/pre>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Vi siete mai soffermati ad osservare la metamorfosi del nostro orizzonte? Quello che un tempo era un azzurro profondo e cristallino ha ceduto il passo ad una foschia lattiginosa, una &#8220;\ud835\ude29\ud835\ude22\ud835\ude3b\ud835\ude26&#8221; persistente che sembra soffocare la nitidezza dei pomeriggi solari. Non si tratta di un mero mutamento meteorologico, bens\u00ec di un segnale visibile di una trasformazione ben pi\u00f9 profonda.<\/div>\n<div dir=\"auto\">E se la narrazione canonica sul riscaldamento globale fosse, nel migliore dei casi, un\u2019omissione parziale e, nel peggiore, una deliberata architettura del silenzio? Le indagini del <strong>Dott. J. Marvin Herndon<\/strong>, fisico nucleare, e del <strong>Dott. Mark Whiteside<\/strong> delineano (<span class=\"html-span xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl x1hl2dhg x16tdsg8 x1vvkbs\"><a class=\"x1i10hfl xjbqb8w x1ejq31n x18oe1m7 x1sy0etr xstzfhl x972fbf x10w94by x1qhh985 x14e42zd x9f619 x1ypdohk xt0psk2 x3ct3a4 xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz xkrqix3 x1sur9pj x1fey0fg x1s688f\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.tankerenemy.com\/2019\/09\/polvere-di-carbone-grafite-magnetite-e.html?fbclid=IwcGRvZgVleHRuA2FlbQIxMABicmlkETFZempoTE92WEI2bXpKbTVBc3J0YwZhcHBfaWQQMjIyMDM5MTc4ODIwMDg5MgABHhy53GflWxhqywSSh9WGD1jrTK7vbQy5YaQCpjhvuyEP6cbjqUDYUluHCjAe_aem_Hj785NykOjYedgrY0jwXQg\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">https:\/\/www.tankerenemy.com\/&#8230;\/polvere-di-carbone&#8230;<\/a><\/span>) uno scenario in cui la causa del surriscaldamento planetario risiede in fattori che la scienza ufficiale continua a ignorare.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<h2 dir=\"auto\">\ud835\udddf\ud835\uddee \ud835\uddfa\ud835\uddf2\ud835\uddfb\ud835\ude07\ud835\uddfc\ud835\uddf4\ud835\uddfb\ud835\uddee \ud835\uddf1\ud835\uddf2\ud835\uddf9 \ud835\uddd6\ud835\udde2\ud835\udfee: \ud835\uddf9\ud835\uddee \ud835\uddda\ud835\uddf2\ud835\uddfc\ud835\uddf6\ud835\uddfb\ud835\uddf4\ud835\uddf2\ud835\uddf4\ud835\uddfb\ud835\uddf2\ud835\uddff\ud835\uddf6\ud835\uddee \ud835\uddf2\ud835\uddf1 \ud835\uddf6\ud835\uddf9 \ud835\uddf0\ud835\uddfc\ud835\uddf9\ud835\uddf9\ud835\uddee\ud835\ude00\ud835\ude00\ud835\uddfc \ud835\uddf1\ud835\uddf2\ud835\uddf9\ud835\uddf9\ud835\uddee \ud835\uddf0\ud835\uddfc\ud835\uddfb\ud835\ude03\ud835\uddf2n\ud835\ude07\ud835\uddf6\ud835\uddfc\ud835\uddfb\ud835\uddf2<\/h2>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">La tesi centrale del lavoro di <strong>Herndon<\/strong> e <strong>Whiteside<\/strong> non si limita a contestare le emissioni di carbonio, ma propone un cambio di paradigma radicale: il riscaldamento globale non \u00e8 l&#8217;esito di una passiva ritenzione di calore dovuta al gas vitale per la terra CO2, ma il risultato di un assorbimento attivo della radiazione solare ad onde corte e lunghe operato dal particolato aviodisperso troposferico.<\/div>\n<div dir=\"auto\">I risultati pubblicati suggeriscono che l&#8217;inquinamento indotto da aerei civili e militari stia letteralmente surriscaldando la troposfera, ostacolando la cruciale rimozione del calore atmosferico-convettivo dalla litosfera. In questo contesto, l&#8217;IPCC e la comunit\u00e0 climatica ufficiale vengono giustamente accusati di una superficialit\u00e0 colpevole.<\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<blockquote>\n<div dir=\"auto\">&#8220;\ud835\udc3f\ud835\udc4e \ud835\udc50\ud835\udc5c\ud835\udc5a\ud835\udc62\ud835\udc5b\ud835\udc56\ud835\udc61\ud835\udc4e\u0300 \ud835\udc51\ud835\udc52\ud835\udc59\ud835\udc59\ud835\udc52 \ud835\udc46\ud835\udc50\ud835\udc56\ud835\udc52\ud835\udc5b\ud835\udc67\ud835\udc52 \ud835\udc51\ud835\udc52\ud835\udc59 \ud835\udc50\ud835\udc59\ud835\udc56\ud835\udc5a\ud835\udc4e \ud835\udc52\ud835\udc51 \ud835\udc56\ud835\udc59 \ud835\udc3a\ud835\udc5f\ud835\udc62\ud835\udc5d\ud835\udc5d\ud835\udc5c \ud835\udc56\ud835\udc5b\ud835\udc61\ud835\udc52\ud835\udc5f\ud835\udc54\ud835\udc5c\ud835\udc63\ud835\udc52\ud835\udc5f\ud835\udc5b\ud835\udc4e\ud835\udc61\ud835\udc56\ud835\udc63\ud835\udc5c \ud835\udc51\ud835\udc52\ud835\udc59\ud835\udc59\ud835\udc52 \ud835\udc41\ud835\udc4e\ud835\udc67\ud835\udc56\ud835\udc5c\ud835\udc5b\ud835\udc56 \ud835\udc48\ud835\udc5b\ud835\udc56\ud835\udc61\ud835\udc52 \ud835\udc60\ud835\udc62\ud835\udc56 \ud835\udc50\ud835\udc4e\ud835\udc5a\ud835\udc4f\ud835\udc56\ud835\udc4e\ud835\udc5a\ud835\udc52\ud835\udc5b\ud835\udc61\ud835\udc56 \ud835\udc50\ud835\udc59\ud835\udc56\ud835\udc5a\ud835\udc4e\ud835\udc61\ud835\udc56\ud835\udc50\ud835\udc56 \u210e\ud835\udc4e\ud835\udc5b\ud835\udc5b\ud835\udc5c \ud835\udc51\ud835\udc56\ud835\udc60\ud835\udc56\ud835\udc5b\ud835\udc53\ud835\udc5c\ud835\udc5f\ud835\udc5a\ud835\udc4e\ud835\udc61\ud835\udc5c \ud835\udc56 \ud835\udc54\ud835\udc5c\ud835\udc63\ud835\udc52\ud835\udc5f\ud835\udc5b\ud835\udc56 \ud835\udc51\ud835\udc52\ud835\udc59 \ud835\udc5a\ud835\udc5c\ud835\udc5b\ud835\udc51\ud835\udc5c, \ud835\udc5b\ud835\udc5c\ud835\udc5b \ud835\udc5f\ud835\udc56\ud835\udc50\ud835\udc5c\ud835\udc5b\ud835\udc5c\ud835\udc60\ud835\udc50\ud835\udc52\ud835\udc5b\ud835\udc51\ud835\udc5c \ud835\udc59\ud835\udc4e \ud835\udc54\ud835\udc52\ud835\udc5c\ud835\udc56\ud835\udc5b\ud835\udc54\ud835\udc52\ud835\udc54\ud835\udc5b\ud835\udc52\ud835\udc5f\ud835\udc56\ud835\udc4e \ud835\udc51\ud835\udc52\ud835\udc59 \ud835\udc5d\ud835\udc4e\ud835\udc5f\ud835\udc61\ud835\udc56\ud835\udc50\ud835\udc5c\ud835\udc59\ud835\udc4e\ud835\udc61\ud835\udc5c \ud835\udc61\ud835\udc5f\ud835\udc5c\ud835\udc5d\ud835\udc5c\ud835\udc60\ud835\udc53\ud835\udc52\ud835\udc5f\ud835\udc56\ud835\udc50\ud835\udc5c \ud835\udc50\u210e\ud835\udc52 \ud835\udc52\u0300 \ud835\udc56\ud835\udc5b \ud835\udc50\ud835\udc5c\ud835\udc5f\ud835\udc60\ud835\udc5c \ud835\udc51\ud835\udc4e \ud835\udc51\ud835\udc52\ud835\udc50\ud835\udc52\ud835\udc5b\ud835\udc5b\ud835\udc56 \ud835\udc50\ud835\udc5c\ud835\udc5b \ud835\udc56\ud835\udc5b\ud835\udc61\ud835\udc52\ud835\udc5b\ud835\udc60\ud835\udc56\ud835\udc61\ud835\udc4e\u0300 \ud835\udc52 \ud835\udc51\ud835\udc62\ud835\udc5f\ud835\udc4e\ud835\udc61\ud835\udc4e \ud835\udc60\ud835\udc52\ud835\udc5a\ud835\udc5d\ud835\udc5f\ud835\udc52 \ud835\udc50\ud835\udc5f\ud835\udc52\ud835\udc60\ud835\udc50\ud835\udc52\ud835\udc5b\ud835\udc61\ud835\udc56 \ud835\udc52 \ud835\udc61\ud835\udc5f\ud835\udc4e\ud835\udc61\ud835\udc61\ud835\udc4e\ud835\udc5b\ud835\udc51\ud835\udc5c \ud835\udc56\ud835\udc59 \ud835\udc5f\ud835\udc56\ud835\udc60\ud835\udc50\ud835\udc4e\ud835\udc59\ud835\udc51\ud835\udc4e\ud835\udc5a\ud835\udc52\ud835\udc5b\ud835\udc61\ud835\udc5c \ud835\udc54\ud835\udc59\ud835\udc5c\ud835\udc4f\ud835\udc4e\ud835\udc59\ud835\udc52 \ud835\udc52\ud835\udc60\ud835\udc50\ud835\udc59\ud835\udc62\ud835\udc60\ud835\udc56\ud835\udc63\ud835\udc4e\ud835\udc5a\ud835\udc52\ud835\udc5b\ud835\udc61\ud835\udc52 \ud835\udc50\ud835\udc5c\ud835\udc5a\ud835\udc52 \ud835\udc62\ud835\udc5b \ud835\udc4f\ud835\udc56\ud835\udc59\ud835\udc4e\ud835\udc5b\ud835\udc50\ud835\udc56\ud835\udc5c \ud835\udc51\ud835\udc52\ud835\udc59\ud835\udc59\ud835\udc52 \ud835\udc5f\ud835\udc4e\ud835\udc51\ud835\udc56\ud835\udc4e\ud835\udc67\ud835\udc56\ud835\udc5c\ud835\udc5b\ud835\udc56&#8221;.<\/div>\n<\/blockquote>\n<div dir=\"auto\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-89295 aligncenter\" src=\"https:\/\/www.liberopensare.com\/wp-content\/uploads\/2026\/09\/2-300x167.jpeg\" alt=\"\" width=\"699\" height=\"389\" srcset=\"https:\/\/www.liberopensare.com\/wp-content\/uploads\/2026\/09\/2-300x167.jpeg 300w, https:\/\/www.liberopensare.com\/wp-content\/uploads\/2026\/09\/2-1024x572.jpeg 1024w, https:\/\/www.liberopensare.com\/wp-content\/uploads\/2026\/09\/2-768x429.jpeg 768w, https:\/\/www.liberopensare.com\/wp-content\/uploads\/2026\/09\/2-1536x857.jpeg 1536w, https:\/\/www.liberopensare.com\/wp-content\/uploads\/2026\/09\/2-18x10.jpeg 18w, https:\/\/www.liberopensare.com\/wp-content\/uploads\/2026\/09\/2-1320x737.jpeg 1320w, https:\/\/www.liberopensare.com\/wp-content\/uploads\/2026\/09\/2.jpeg 2048w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/><\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<h2 dir=\"auto\">\ud835\udddc\ud835\uddf9 \ud835\uddf0\ud835\uddfc\ud835\uddf0\ud835\uddf8\ud835\ude01\ud835\uddee\ud835\uddf6\ud835\uddf9 \ud835\uddf0\ud835\uddf5\ud835\uddf6\ud835\uddfa\ud835\uddf6\ud835\uddf0\ud835\uddfc: \ud835\uddff\ud835\uddee\ud835\uddf1\ud835\uddf6\ud835\uddee\ud835\uddfb\ud835\ude01\ud835\uddf6 \ud835\uddee\ud835\uddff\ud835\ude01\ud835\uddf6\ud835\uddf3\ud835\uddf6\ud835\uddf0\ud835\uddf6\ud835\uddee\ud835\uddf9\ud835\uddf6 \ud835\uddf6\ud835\uddfb \ud835\uddee\ud835\ude01\ud835\uddfa\ud835\uddfc\ud835\ude00\ud835\uddf3\ud835\uddf2\ud835\uddff\ud835\uddee<\/h2>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Secondo le analisi di <strong>Herndon<\/strong> e <strong>Whiteside<\/strong>, il nostro cielo \u00e8 diventato il laboratorio privilegiato per la diffusione di materiali ottimizzati per l&#8217;assorbimento energetico. La fonte identifica un mix preciso di composti tossici: cenere volante di carbone (coal fly ash), ematite (grafene), magnetite e ferro.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">\n<figure id=\"attachment_89235\" aria-describedby=\"caption-attachment-89235\" style=\"width: 476px\" class=\"wp-caption alignleft\"><img decoding=\"async\" class=\"wp-image-89235\" src=\"https:\/\/www.liberopensare.com\/wp-content\/uploads\/2026\/08\/JvH-214x300.jpg\" alt=\"\" width=\"476\" height=\"667\" srcset=\"https:\/\/www.liberopensare.com\/wp-content\/uploads\/2026\/08\/JvH-214x300.jpg 214w, https:\/\/www.liberopensare.com\/wp-content\/uploads\/2026\/08\/JvH-9x12.jpg 9w, https:\/\/www.liberopensare.com\/wp-content\/uploads\/2026\/08\/JvH.jpg 731w\" sizes=\"(max-width: 476px) 100vw, 476px\" \/><figcaption id=\"caption-attachment-89235\" class=\"wp-caption-text\"><a href=\"https:\/\/edizioniartemis.it\/prodotti\/rudolf-steiner-maestro-della-loggia-bianca\/ref\/3\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #800000;\"><strong>NOVIT\u00c0! ACQUISTALO QUI IN PREVENDITA CON IL 15% DI SCONTO!<\/strong><\/span><\/a><\/figcaption><\/figure>\n<p>Questi elementi non sono neutrali rispetto allo spettro solare. Il carbonio nero (black carbon) assorbe radiazioni sull&#8217;intero spettro solare, mentre il carbonio marrone e gli ossidi di ferro intercettano le frequenze vicine agli UV e alla luce visibile, trasformando l&#8217;atmosfera in un accumulatore termico che impedisce alla Terra di raffreddarsi naturalmente durante la notte.<\/p>\n<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<h2 dir=\"auto\">\ud835\uddd7\ud835\uddff\ud835\uddfc\ud835\uddfb\ud835\uddf6 \ud835\uddf2 \ud835\uddfd\ud835\uddff\ud835\uddfc\ud835\ude03\ud835\uddf2 \ud835\uddf6\ud835\uddfb\ud835\uddf1\ud835\uddf6\ud835\uddff\ud835\uddf2\ud835\ude01\ud835\ude01\ud835\uddf2: \ud835\uddf9&#8217;\ud835\uddf2\ud835\ude03\ud835\uddf6\ud835\uddf1\ud835\uddf2\ud835\uddfb\ud835\ude07\ud835\uddee \ud835\uddf1\ud835\uddf2\ud835\uddf9 \ud835\uddfd\ud835\uddee\ud835\uddff\ud835\ude01\ud835\uddf6\ud835\uddf0\ud835\uddfc\ud835\uddf9\ud835\uddee\ud835\ude01\ud835\uddfc \ud835\uddfa\ud835\uddf2\ud835\ude01\ud835\uddee\ud835\uddf9\ud835\uddf9\ud835\uddf6\ud835\uddf0\ud835\uddfc<\/h2>\n<div dir=\"auto\"><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\">L&#8217;indagine scientifica condotta da <strong>Antonio<\/strong> e <strong>Rosario Marcian\u00f2<\/strong> del Comitato Tanker enemy trova riscontri empirici anche a quote elevate. Un episodio emblematico riportato descrive il volo di un drone DJI a 1600 metri di altitudine, nel cuore di cumuli nuvolosi lontani da ogni interferenza antropica. Il malfunzionamento sistematico della bussola di bordo suggerisce la presenza di un aerosol metallico capace di perturbare i sensori magnetici, come se il velivolo fosse accostato a masse ferrose. <\/span><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\">Per il comune cittadino, la prova \u00e8 spesso a portata di mano: \u00e8 sufficiente una calamita per estrarre polveri magnetiche dalle carrozzerie delle auto dopo una pioggia, segno tangibile di ci\u00f2 che precipita dai nostri cieli.<\/span><\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Oltre a questi test locali, Herndon cita tre linee di evidenza indipendenti che elevano il sospetto a certezza documentale: il comportamento dei pennacchi vulcanici del Monte Sant\u2019Elena, le indagini spettroscopiche (etalometro) condotte da <strong>Talukdar<\/strong> e, infine, l\u2019osservazione della soppressione della convezione sull\u2019Atlantico settentrionale provocata dalle polveri.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Tutto converge verso una singola realt\u00e0: il particolato sopprime la naturale dinamica di raffreddamento del pianeta.<\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<h2 dir=\"auto\">\ud835\udddf\u2019\ud835\uddee\ud835\uddff\ud835\uddf0\ud835\uddf5\ud835\uddf6\ud835\ude01\ud835\uddf2\ud835\ude01\ud835\ude01\ud835\ude02\ud835\uddff\ud835\uddee \ud835\uddf1\ud835\uddf2\ud835\uddf9 \ud835\uddf0\ud835\uddee\ud835\uddf9\ud835\uddfc\ud835\uddff\ud835\uddf2: \ud835\uddf9\ud835\uddee &#8220;\ud835\uddf0\ud835\ude02\ud835\uddfd\ud835\uddfc\ud835\uddf9\ud835\uddee&#8221; \ud835\uddf2\ud835\uddf1 \ud835\uddf6\ud835\uddf9 \ud835\uddef\ud835\uddf6\ud835\uddfc\ud835\uddf0\ud835\uddf6\ud835\uddf1\ud835\uddf6\ud835\uddfc \ud835\ude00\ud835\uddf6\ud835\uddf9\ud835\uddf2\ud835\uddfb\ud835\ude07\ud835\uddf6\ud835\uddfc\ud835\ude00\ud835\uddfc<\/h2>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<figure id=\"attachment_89210\" aria-describedby=\"caption-attachment-89210\" style=\"width: 496px\" class=\"wp-caption alignright\"><img decoding=\"async\" class=\"wp-image-89210\" src=\"https:\/\/www.liberopensare.com\/wp-content\/uploads\/2026\/08\/LAFERITA-214x300.png\" alt=\"\" width=\"496\" height=\"695\" srcset=\"https:\/\/www.liberopensare.com\/wp-content\/uploads\/2026\/08\/LAFERITA-214x300.png 214w, https:\/\/www.liberopensare.com\/wp-content\/uploads\/2026\/08\/LAFERITA-9x12.png 9w, https:\/\/www.liberopensare.com\/wp-content\/uploads\/2026\/08\/LAFERITA.png 731w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/><figcaption id=\"caption-attachment-89210\" class=\"wp-caption-text\"><a href=\"https:\/\/edizioniartemis.it\/prodotti\/la-ferita\/ref\/3\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #800000;\"><strong>NOVIT\u00c0! ACQUISTALO QUI IN PREVENDITA CON IL 15% DI SCONTO!<\/strong><\/span><\/a><\/figcaption><\/figure>\n<p>La manipolazione climatica regionale sembra aver raggiunto una maturit\u00e0 tecnica inquietante attraverso l&#8217;uso delle Light-Absorbing Particles (LAP). Iniettando massicce dosi di particolato carbonioso o fuliggine nella troposfera, \u00e8 possibile generare una stazionariet\u00e0 artificiale delle masse d&#8217;aria, creando cupole di calore persistenti. Questo fenomeno spiega la recente intensit\u00e0 delle ondate di calore europee, accompagnate da alterazioni ottiche (albe e tramonti occultati da pesanti nebbie di ricaduta) e olfattive, come il diffuso odore di bruciato segnalato in aree prive di incendi locali. Siamo di fronte a quello che molti definiscono un &#8220;biocidio&#8221;, una modifica orrenda dell&#8217;ecosistema che accelera la distruzione dell&#8217;ozono atmosferico ed altera i processi vitali di base.<\/p>\n<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<h2 dir=\"auto\">\ud835\udde3\ud835\uddff\ud835\uddfc\ud835\ude01\ud835\uddfc\ud835\uddf0\ud835\uddfc\ud835\uddf9\ud835\uddf9\ud835\uddfc \ud835\uddf1\ud835\uddf6 \ud835\ude00\ud835\uddfc\ud835\uddfd\ud835\uddff\ud835\uddee\ud835\ude03\ud835\ude03\ud835\uddf6\ud835\ude03\ud835\uddf2\ud835\uddfb\ud835\ude07\ud835\uddee: \ud835\uddf3\ud835\uddf2\ud835\uddff\ud835\uddfa\ud835\uddee\ud835\uddff\ud835\uddf2 \ud835\uddf9&#8217;\ud835\uddf2\ud835\ude00\ud835\ude01\ud835\uddf6\ud835\uddfb\ud835\ude07\ud835\uddf6\ud835\uddfc\ud835\uddfb\ud835\uddf2<\/h2>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Per invertire questa traiettoria che conduce all&#8217;estinzione, <strong>Herndon<\/strong> e <strong>Whiteside<\/strong> propongono un protocollo d&#8217;emergenza non negoziabile:<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">* \ud835\udc70\ud835\udc8f\ud835\udc95\ud835\udc86\ud835\udc93\ud835\udc93\ud835\udc96\ud835\udc9b\ud835\udc8a\ud835\udc90\ud835\udc8f\ud835\udc86 \ud835\udc8a\ud835\udc8e\ud835\udc8e\ud835\udc86\ud835\udc85\ud835\udc8a\ud835\udc82\ud835\udc95\ud835\udc82 \ud835\udc85\ud835\udc8a \ud835\udc90\ud835\udc88\ud835\udc8f\ud835\udc8a \ud835\udc82\ud835\udc95\ud835\udc95\ud835\udc8a\ud835\udc97\ud835\udc8a\ud835\udc95\ud835\udc82\u0300 \ud835\udc85\ud835\udc8a \ud835\udc88\ud835\udc86\ud835\udc90\ud835\udc8a\ud835\udc8f\ud835\udc88\ud835\udc86\ud835\udc88\ud835\udc8f\ud835\udc86\ud835\udc93\ud835\udc8a\ud835\udc82 \ud835\udc85\ud835\udc86\ud835\udc8d \ud835\udc91\ud835\udc82\ud835\udc93\ud835\udc95\ud835\udc8a\ud835\udc84\ud835\udc90\ud835\udc8d\ud835\udc82\ud835\udc95\ud835\udc90 \ud835\udc95\ud835\udc93\ud835\udc90\ud835\udc91\ud835\udc90\ud835\udc94\ud835\udc87\ud835\udc86\ud835\udc93\ud835\udc8a\ud835\udc84\ud835\udc90 \ud835\udc86 \ud835\udc85\ud835\udc86\ud835\udc8d\ud835\udc8d\ud835\udc86 \ud835\udc8a\ud835\udc93\ud835\udc93\ud835\udc90\ud835\udc93\ud835\udc82\ud835\udc9b\ud835\udc8a\ud835\udc90\ud835\udc8f\ud835\udc8a \ud835\udc84\ud835\udc8d\ud835\udc82\ud835\udc8f\ud835\udc85\ud835\udc86\ud835\udc94\ud835\udc95\ud835\udc8a\ud835\udc8f\ud835\udc86 (\ud835\udc94\ud835\udc84\ud835\udc8a\ud835\udc86 \ud835\udc84\ud835\udc89\ud835\udc8a\ud835\udc8e\ud835\udc8a\ud835\udc84\ud835\udc89\ud835\udc86).<\/div>\n<div dir=\"auto\">* \ud835\udc6c\ud835\udc8d\ud835\udc8a\ud835\udc8e\ud835\udc8a\ud835\udc8f\ud835\udc82\ud835\udc9b\ud835\udc8a\ud835\udc90\ud835\udc8f\ud835\udc86 \ud835\udc85\ud835\udc86\ud835\udc88\ud835\udc8d\ud835\udc8a \ud835\udc82\ud835\udc85\ud835\udc85\ud835\udc8a\ud835\udc95\ud835\udc8a\ud835\udc97\ud835\udc8a \ud835\udc8f\ud835\udc86\ud835\udc8a \ud835\udc84\ud835\udc82\ud835\udc93\ud835\udc83\ud835\udc96\ud835\udc93\ud835\udc82\ud835\udc8f\ud835\udc95\ud835\udc8a (\ud835\udc94\ud835\udc8a\ud835\udc82 \ud835\udc82\ud835\udc97\ud835\udc8a\ud835\udc90 \ud835\udc84\ud835\udc89\ud835\udc86 \ud835\udc95\ud835\udc86\ud835\udc93\ud835\udc93\ud835\udc86\ud835\udc94\ud835\udc95\ud835\udc93\ud835\udc8a) \ud835\udc84\ud835\udc89\ud835\udc86 \ud835\udc82\ud835\udc88\ud835\udc8a\ud835\udc94\ud835\udc84\ud835\udc90\ud835\udc8f\ud835\udc90 \ud835\udc84\ud835\udc90\ud835\udc8e\ud835\udc86 \ud835\udc91\ud835\udc93\ud835\udc86\ud835\udc84\ud835\udc96\ud835\udc93\ud835\udc94\ud835\udc90\ud835\udc93\ud835\udc8a \ud835\udc85\ud835\udc86\ud835\udc8d \ud835\udc91\ud835\udc82\ud835\udc93\ud835\udc95\ud835\udc8a\ud835\udc84\ud835\udc90\ud835\udc8d\ud835\udc82\ud835\udc95\ud835\udc90.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">La verit\u00e0 \u00e8 dunque spesso pi\u00f9 semplice e pi\u00f9 brutale di quanto le complesse proiezioni algoritmiche dei governi vogliano ammettere.<\/div>\n<div dir=\"auto\">Il recupero della nostra biosfera passa per la denuncia di questa architettura artificiale del calore. In questo scenario di ecosistema artificializzato, pratiche come l&#8217;Earthing \u2014 il ricollegarsi fisicamente e biopoliticamente alla Terra \u2014 smettono di essere curiosit\u00e0 olistiche per diventare atti di resistenza necessari.<\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">La prossima volta che alzerete lo sguardo verso una scia (persistente o evanescente) che si sfrangia in una coltre biancastra, ricordate che state osservando il velo artificiale che ci separa dalla convezione naturale. Guardare il cielo con occhi diversi non \u00e8 solo un atto di consapevolezza; \u00e8 il primo passo per tornare a respirare un futuro che non sia stato deciso a tavolino da infami senza volto.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>di Rosario Marcian\u00f2 Vi siete mai soffermati ad osservare la metamorfosi del nostro orizzonte? Quello che un tempo era un azzurro profondo e cristallino ha ceduto il passo ad una foschia lattiginosa, una &#8220;\ud835\ude29\ud835\ude22\ud835\ude3b\ud835\ude26&#8221; persistente che sembra soffocare la nitidezza dei pomeriggi solari. Non si tratta di un mero mutamento meteorologico, bens\u00ec di un segnale [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":89294,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5166,903],"tags":[7689,1048,7477,7646,7687,7688,7686,7685,7690],"class_list":["post-89293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-e-scienza","category-rassegna","tag-antonio-marciano","tag-boxgranderassegna","tag-caldo","tag-clima","tag-dott-j-marvin-herndon","tag-dott-mark-whiteside","tag-nebbia","tag-rosario-marciano","tag-talukdar"],"_links":{"self":[{"href":"https:\/\/www.liberopensare.com\/en\/wp-json\/wp\/v2\/posts\/89293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.liberopensare.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.liberopensare.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.liberopensare.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.liberopensare.com\/en\/wp-json\/wp\/v2\/comments?post=89293"}],"version-history":[{"count":4,"href":"https:\/\/www.liberopensare.com\/en\/wp-json\/wp\/v2\/posts\/89293\/revisions"}],"predecessor-version":[{"id":89299,"href":"https:\/\/www.liberopensare.com\/en\/wp-json\/wp\/v2\/posts\/89293\/revisions\/89299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.liberopensare.com\/en\/wp-json\/wp\/v2\/media\/89294"}],"wp:attachment":[{"href":"https:\/\/www.liberopensare.com\/en\/wp-json\/wp\/v2\/media?parent=89293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.liberopensare.com\/en\/wp-json\/wp\/v2\/categories?post=89293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.liberopensare.com\/en\/wp-json\/wp\/v2\/tags?post=89293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}